{"id":2478,"date":"2021-04-01T08:44:54","date_gmt":"2021-04-01T05:44:54","guid":{"rendered":"http:\/\/poloscarsparos.gr\/?page_id=2478"},"modified":"2024-07-16T08:12:37","modified_gmt":"2024-07-16T05:12:37","slug":"offerte","status":"publish","type":"page","link":"https:\/\/poloscarsparos.gr\/it\/offerte\/","title":{"rendered":"Offerte"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\"><strong><strong>Offerte di Noleggio Stagionali<\/strong><\/strong><\/h4>\n\n\n\n<p><em><em>Tutti gli sconti delle Offerte Stagionali sono disponibili online sul motore di prenotazione. (Prezzi finali, Nessun coupon richiesto)<\/em><\/em><\/p>\n\n\n\n<p><strong><strong>La nostra Politica riguardante i Noleggi a breve termine:<\/strong> (3-7 giorni)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>10% di sconto per noleggi da 3 a 7 giorni, per tutti i veicoli disponibili<\/li>\n\n\n\n<li>30% di anticipo dell'importo totale per riservare il veicolo<\/li>\n\n\n\n<li>Politica di cancellazione di 10 giorni per un rimborso del 100% (30% di penale di cancellazione entro 10 giorni prima del ritiro)<\/li>\n\n\n\n<li>ulteriore 10% di sconto per prenotazioni non rimborsabili. Pagamento anticipato del 100% dell'importo totale e almeno 90 giorni prima del ritiro (SOLO via email)<\/li>\n<\/ul>\n\n\n\n<p><strong><strong>La nostra Politica riguardante i Noleggi a lungo termine:<\/strong> (8-21 giorni)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>15% di sconto per noleggi da 8 a 21 giorni, per tutti i veicoli disponibili<\/li>\n\n\n\n<li>30% di anticipo dell'importo totale per riservare il veicolo<\/li>\n\n\n\n<li>Politica di cancellazione di 15 giorni per un rimborso del 100% (30% di penale di cancellazione entro 15 giorni prima del ritiro)<\/li>\n\n\n\n<li>Ulteriore 10% di sconto per prenotazioni non rimborsabili. Pagamento anticipato del 100% dell'importo totale e almeno 90 giorni prima del ritiro (SOLO via email)<\/li>\n<\/ul>\n\n\n\n<p><strong><strong>La nostra Politica riguardante i Noleggi mensili a lungo termine<\/strong>: (30 giorni e oltre)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>40% \u2013 60% di sconto per noleggi superiori a 30 giorni, solo per specifiche categorie di veicoli<\/li>\n\n\n\n<li>Pagamento anticipato del 100% di ogni mese<\/li>\n\n\n\n<li>Nessuna penale di cancellazione<\/li>\n\n\n\n<li>Disponibilit\u00e0 e prezzi SOLO via email<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Offerte speciali<\/strong><\/h4>\n\n\n\n<p><em>Offerte casuali e limitate con un ottimo rapporto qualit\u00e0-prezzo!<\/em><\/p>\n\n\n\n\n<div class=\"wrap plugin-container\">\n\n\t\n\t\n\t\t<h3>Nessuna Promozione Attiva<\/h3>\r\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Offerte di Noleggio Stagionali Tutti gli sconti delle Offerte Stagionali sono disponibili online sul motore di prenotazione. (Prezzi finali, Nessun coupon richiesto) La nostra Politica riguardante i Noleggi a breve termine: (3-7 giorni) La nostra Politica riguardante i Noleggi a lungo termine: (8-21 giorni) La nostra Politica riguardante i Noleggi mensili a lungo termine: (30 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/poloscarsparos.gr\/it\/offerte\/\" class=\"more-link\"><span class=\"screen-reader-text\"> prova \"Offerte\"<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3428,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2478","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offerte \/ Sconti per il noleggio auto a Paros.<\/title>\n<meta name=\"description\" content=\"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poloscarsparos.gr\/it\/offerte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offerte \/ Sconti per il noleggio auto a Paros.\" \/>\n<meta property=\"og:description\" content=\"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poloscarsparos.gr\/it\/offerte\/\" \/>\n<meta property=\"og:site_name\" content=\"Polos Rent A Car &amp; Rental Agency in Paros\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T05:12:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/\",\"url\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/\",\"name\":\"Offerte \/ Sconti per il noleggio auto a Paros.\",\"isPartOf\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg\",\"datePublished\":\"2021-04-01T05:44:54+00:00\",\"dateModified\":\"2024-07-16T05:12:37+00:00\",\"description\":\"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.\",\"breadcrumb\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/poloscarsparos.gr\/it\/offerte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage\",\"url\":\"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg\",\"contentUrl\":\"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg\",\"width\":1800,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/offerte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poloscarsparos.gr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#website\",\"url\":\"https:\/\/poloscarsparos.gr\/it\/\",\"name\":\"Polos Rent A Car &amp; Rental Agency in Paros\",\"description\":\"Rent a car, buggy, quad \/ atv, scooter  in Paros\",\"publisher\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poloscarsparos.gr\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#organization\",\"name\":\"Polos Rent A Car & Rental Agency\",\"url\":\"https:\/\/poloscarsparos.gr\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Polos Rent A Car & Rental Agency\"},\"image\":{\"@id\":\"https:\/\/poloscarsparos.gr\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offerte \/ Sconti per il noleggio auto a Paros.","description":"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poloscarsparos.gr\/it\/offerte\/","og_locale":"it_IT","og_type":"article","og_title":"Offerte \/ Sconti per il noleggio auto a Paros.","og_description":"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.","og_url":"https:\/\/poloscarsparos.gr\/it\/offerte\/","og_site_name":"Polos Rent A Car &amp; Rental Agency in Paros","article_modified_time":"2024-07-16T05:12:37+00:00","og_image":[{"width":1800,"height":467,"url":"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/","url":"https:\/\/poloscarsparos.gr\/it\/offerte\/","name":"Offerte \/ Sconti per il noleggio auto a Paros.","isPartOf":{"@id":"https:\/\/poloscarsparos.gr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage"},"image":{"@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage"},"thumbnailUrl":"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg","datePublished":"2021-04-01T05:44:54+00:00","dateModified":"2024-07-16T05:12:37+00:00","description":"Offerte stagionali e sconti speciali per un lungo periodo di noleggio auto, quad, buggy, scooter e moto a Paros con proffito al miglior prezzo per voi.","breadcrumb":{"@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/poloscarsparos.gr\/it\/offerte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/#primaryimage","url":"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg","contentUrl":"https:\/\/poloscarsparos.gr\/wp-content\/uploads\/2022\/03\/offers-1.jpg","width":1800,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/poloscarsparos.gr\/it\/offerte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poloscarsparos.gr\/it\/"},{"@type":"ListItem","position":2,"name":"Offerte"}]},{"@type":"WebSite","@id":"https:\/\/poloscarsparos.gr\/it\/#website","url":"https:\/\/poloscarsparos.gr\/it\/","name":"Polos Rent A Car &amp; Rental Agency in Paros","description":"Rent a car, buggy, quad \/ atv, scooter  in Paros","publisher":{"@id":"https:\/\/poloscarsparos.gr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poloscarsparos.gr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/poloscarsparos.gr\/it\/#organization","name":"Polos Rent A Car & Rental Agency","url":"https:\/\/poloscarsparos.gr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/poloscarsparos.gr\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Polos Rent A Car & Rental Agency"},"image":{"@id":"https:\/\/poloscarsparos.gr\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/pages\/2478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/comments?post=2478"}],"version-history":[{"count":9,"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/pages\/2478\/revisions"}],"predecessor-version":[{"id":5649,"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/pages\/2478\/revisions\/5649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/media\/3428"}],"wp:attachment":[{"href":"https:\/\/poloscarsparos.gr\/it\/wp-json\/wp\/v2\/media?parent=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}